{"id":337,"count":7,"description":"","link":"https:\/\/www.topdevelopers.co\/blog\/category\/uiux-design\/","name":"UI\/UX design","slug":"uiux-design","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.topdevelopers.co\/blog\/wp-json\/wp\/v2\/categories\/337"}],"collection":[{"href":"https:\/\/www.topdevelopers.co\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.topdevelopers.co\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.topdevelopers.co\/blog\/wp-json\/wp\/v2\/posts?categories=337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}